{"id":190,"date":"2025-05-19T15:33:31","date_gmt":"2025-05-19T15:33:31","guid":{"rendered":"https:\/\/zenwood.es\/?page_id=190"},"modified":"2025-09-29T07:41:51","modified_gmt":"2025-09-29T07:41:51","slug":"madera-sostenible","status":"publish","type":"page","link":"https:\/\/zenwood.es\/ca\/madera-sostenible\/","title":{"rendered":"SOSTENIBILITAT"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"190\" class=\"elementor elementor-190\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3e539aa e-flex e-con-boxed e-con e-parent\" data-id=\"3e539aa\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-a1de5a7 e-con-full e-flex e-con e-child\" data-id=\"a1de5a7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5670d06 elementor-widget elementor-widget-heading\" data-id=\"5670d06\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Sostenibilitat<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-19d38f1 elementor-widget elementor-widget-shortcode\" data-id=\"19d38f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><span><span><a href=\"https:\/\/zenwood.es\/ca\/\">Portada<\/a><\/span><\/span><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e820547 e-con-full e-flex e-con e-child\" data-id=\"e820547\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b0ee185 elementor-widget elementor-widget-image\" data-id=\"b0ee185\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"438\" height=\"471\" src=\"https:\/\/zenwood.es\/wp-content\/uploads\/2025\/05\/Frame-50.png\" class=\"attachment-large size-large wp-image-181\" alt=\"Logo Zenwood \u2013 Especialistas en madera quemada Yakisugi\" srcset=\"https:\/\/zenwood.es\/wp-content\/uploads\/2025\/05\/Frame-50.png.webp 438w, https:\/\/zenwood.es\/wp-content\/uploads\/2025\/05\/Frame-50-279x300.png.webp 279w\" sizes=\"auto, (max-width: 438px) 100vw, 438px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4e3b05b e-flex e-con-boxed e-con e-parent\" data-id=\"4e3b05b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-2a5aac3 e-con-full e-flex e-con e-child\" data-id=\"2a5aac3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-43aa624 elementor-widget elementor-widget-heading\" data-id=\"43aa624\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nuestro Compromiso<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4ef8cde elementor-widget elementor-widget-heading\" data-id=\"4ef8cde\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">En Zenwood, estamos comprometidos con la sostenibilidad en cada aspecto de nuestro negocio. <b>Desde la selecci\u00f3n de materiales hasta la entrega final del producto,<\/b> buscamos constantemente formas innovadoras de reducir nuestro impacto ambiental y promover pr\u00e1cticas m\u00e1s sostenibles en la industria de la construcci\u00f3n.<br><br>\n\nUtilizamos tecnolog\u00edas avanzadas y materiales ecol\u00f3gicos para fabricar nuestros productos, asegurando que cada paso del proceso de producci\u00f3n sea lo m\u00e1s sostenible posible.\nAdem\u00e1s, nos esforzamos por gestionar de manera responsable los recursos naturales y minimizar los residuos, siempre con la meta de mejorar continuamente nuestras pr\u00e1cticas y hacer una contribuci\u00f3n positiva al\nmedio ambiente.\u00a0<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4360d21 elementor-widget elementor-widget-heading\" data-id=\"4360d21\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Liderando el cambio hacia un futuro m\u00e1s verde<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6997541 elementor-widget elementor-widget-heading\" data-id=\"6997541\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">En Zenwood, creemos firmemente en liderar el cambio hacia un futuro m\u00e1s verde y pr\u00f3spero. Estamos dedicados a inspirar a otros en la industria de la construcci\u00f3n a unirse a nosotros en este viaje hacia la sostenibilidad.<br><br>\n\nA trav\u00e9s de nuestro compromiso con pr\u00e1cticas sostenibles y nuestro enfoque en la innovaci\u00f3n ambiental, <b>esperamos marcar la diferencia y dejar un impacto positivo en el mundo que nos rodea.<\/b><\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-349d0ea elementor-align-left elementor-widget elementor-widget-button\" data-id=\"349d0ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/wa.me\/34613099044\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Aconseguiu la vostra mostra<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-34b1f36 e-con-full e-flex e-con e-child\" data-id=\"34b1f36\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1a687bd elementor-widget elementor-widget-image\" data-id=\"1a687bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/zenwood.es\/wp-content\/uploads\/2025\/05\/IMGL5833-1-683x1024.png\" class=\"attachment-large size-large wp-image-193\" alt=\"Zenwood\" srcset=\"https:\/\/zenwood.es\/wp-content\/uploads\/2025\/05\/IMGL5833-1-683x1024.png.webp 683w, https:\/\/zenwood.es\/wp-content\/uploads\/2025\/05\/IMGL5833-1-600x900.png 600w, https:\/\/zenwood.es\/wp-content\/uploads\/2025\/05\/IMGL5833-1-200x300.png.webp 200w, https:\/\/zenwood.es\/wp-content\/uploads\/2025\/05\/IMGL5833-1-768x1152.png.webp 768w, https:\/\/zenwood.es\/wp-content\/uploads\/2025\/05\/IMGL5833-1.png.webp 798w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Sostenibilidad Nuestro Compromiso En Zenwood, estamos comprometidos con la sostenibilidad en cada aspecto de nuestro negocio. Desde la selecci\u00f3n de materiales hasta la entrega final del producto, buscamos constantemente formas innovadoras de reducir nuestro impacto ambiental y promover pr\u00e1cticas m\u00e1s sostenibles en la industria de la construcci\u00f3n. Utilizamos tecnolog\u00edas avanzadas y materiales ecol\u00f3gicos para fabricar [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_joinchat":[],"footnotes":""},"class_list":["post-190","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SOSTENIBILIDAD - Zenwood<\/title>\n<meta name=\"description\" content=\"Madera sostenible para tus proyectos: resistente, certificada y con estilo. Ideal para fachadas, interiores y exteriores.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SOSTENIBILIDAD - Zenwood\" \/>\n<meta property=\"og:description\" content=\"Madera sostenible para tus proyectos: resistente, certificada y con estilo. Ideal para fachadas, interiores y exteriores.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zenwood.es\/ca\/madera-sostenible\/\" \/>\n<meta property=\"og:site_name\" content=\"Zenwood\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/zenwoodes\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-29T07:41:51+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/zenwood.es\/wp-content\/uploads\/2025\/05\/Frame-50.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/zenwood.es\\\/ca\\\/wp-json\\\/wp\\\/v2\\\/pages\\\/190\\\/#webpage\",\"url\":\"https:\\\/\\\/zenwood.es\\\/ca\\\/wp-json\\\/wp\\\/v2\\\/pages\\\/190\\\/\",\"name\":\"SOSTENIBILIDAD - Zenwood\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zenwood.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/zenwood.es\\\/ca\\\/wp-json\\\/wp\\\/v2\\\/pages\\\/190\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/zenwood.es\\\/ca\\\/wp-json\\\/wp\\\/v2\\\/pages\\\/190\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/zenwood.es\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Frame-50.png\",\"datePublished\":\"2025-05-19T15:33:31+00:00\",\"dateModified\":\"2025-09-29T07:41:51+00:00\",\"description\":\"Madera sostenible para tus proyectos: resistente, certificada y con estilo. Ideal para fachadas, interiores y exteriores.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zenwood.es\\\/ca\\\/wp-json\\\/wp\\\/v2\\\/pages\\\/190\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/zenwood.es\\\/ca\\\/wp-json\\\/wp\\\/v2\\\/pages\\\/190\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/zenwood.es\\\/ca\\\/wp-json\\\/wp\\\/v2\\\/pages\\\/190\\\/#primaryimage\",\"url\":\"http:\\\/\\\/zenwood.es\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Frame-50.png\",\"contentUrl\":\"http:\\\/\\\/zenwood.es\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Frame-50.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zenwood.es\\\/ca\\\/wp-json\\\/wp\\\/v2\\\/pages\\\/190\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/zenwood.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SOSTENIBILIDAD\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zenwood.es\\\/#website\",\"url\":\"https:\\\/\\\/zenwood.es\\\/\",\"name\":\"Zenwood\",\"description\":\"touched by nature\",\"publisher\":{\"@id\":\"https:\\\/\\\/zenwood.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zenwood.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/zenwood.es\\\/#organization\",\"name\":\"Zenwood\",\"url\":\"https:\\\/\\\/zenwood.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/zenwood.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/zenwood.es\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/logo-1.png\",\"contentUrl\":\"https:\\\/\\\/zenwood.es\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/logo-1.png\",\"width\":524,\"height\":83,\"caption\":\"Zenwood\"},\"image\":{\"@id\":\"https:\\\/\\\/zenwood.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/zenwoodes\\\/\",\"https:\\\/\\\/www.instagram.com\\\/zenwoodes\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/zenwoodes\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@ZENWOODes\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fusta sostenible per a projectes arquitect\u00f2nics","description":"Madera sostenible para tus proyectos: resistente, certificada y con estilo. Ideal para fachadas, interiores y exteriores.","robots":{"index":"noindex","follow":"follow"},"og_locale":"ca_ES","og_type":"article","og_title":"SOSTENIBILIDAD - Zenwood","og_description":"Madera sostenible para tus proyectos: resistente, certificada y con estilo. Ideal para fachadas, interiores y exteriores.","og_url":"https:\/\/zenwood.es\/ca\/madera-sostenible\/","og_site_name":"Zenwood","article_publisher":"https:\/\/www.facebook.com\/zenwoodes\/","article_modified_time":"2025-09-29T07:41:51+00:00","og_image":[{"url":"http:\/\/zenwood.es\/wp-content\/uploads\/2025\/05\/Frame-50.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Temps estimat de lectura":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/zenwood.es\/ca\/wp-json\/wp\/v2\/pages\/190\/#webpage","url":"https:\/\/zenwood.es\/ca\/wp-json\/wp\/v2\/pages\/190\/","name":"Fusta sostenible per a projectes arquitect\u00f2nics","isPartOf":{"@id":"https:\/\/zenwood.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/zenwood.es\/ca\/wp-json\/wp\/v2\/pages\/190\/#primaryimage"},"image":{"@id":"https:\/\/zenwood.es\/ca\/wp-json\/wp\/v2\/pages\/190\/#primaryimage"},"thumbnailUrl":"http:\/\/zenwood.es\/wp-content\/uploads\/2025\/05\/Frame-50.png","datePublished":"2025-05-19T15:33:31+00:00","dateModified":"2025-09-29T07:41:51+00:00","description":"Madera sostenible para tus proyectos: resistente, certificada y con estilo. Ideal para fachadas, interiores y exteriores.","breadcrumb":{"@id":"https:\/\/zenwood.es\/ca\/wp-json\/wp\/v2\/pages\/190\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/zenwood.es\/ca\/wp-json\/wp\/v2\/pages\/190\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/zenwood.es\/ca\/wp-json\/wp\/v2\/pages\/190\/#primaryimage","url":"http:\/\/zenwood.es\/wp-content\/uploads\/2025\/05\/Frame-50.png","contentUrl":"http:\/\/zenwood.es\/wp-content\/uploads\/2025\/05\/Frame-50.png"},{"@type":"BreadcrumbList","@id":"https:\/\/zenwood.es\/ca\/wp-json\/wp\/v2\/pages\/190\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/zenwood.es\/"},{"@type":"ListItem","position":2,"name":"SOSTENIBILIDAD"}]},{"@type":"WebSite","@id":"https:\/\/zenwood.es\/#website","url":"https:\/\/zenwood.es\/","name":"Zenwood","description":"touched by nature","publisher":{"@id":"https:\/\/zenwood.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zenwood.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/zenwood.es\/#organization","name":"Zenwood","url":"https:\/\/zenwood.es\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/zenwood.es\/#\/schema\/logo\/image\/","url":"https:\/\/zenwood.es\/wp-content\/uploads\/2025\/05\/logo-1.png","contentUrl":"https:\/\/zenwood.es\/wp-content\/uploads\/2025\/05\/logo-1.png","width":524,"height":83,"caption":"Zenwood"},"image":{"@id":"https:\/\/zenwood.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/zenwoodes\/","https:\/\/www.instagram.com\/zenwoodes","https:\/\/www.linkedin.com\/company\/zenwoodes\/","https:\/\/www.youtube.com\/@ZENWOODes"]}]}},"_links":{"self":[{"href":"https:\/\/zenwood.es\/ca\/wp-json\/wp\/v2\/pages\/190","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zenwood.es\/ca\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/zenwood.es\/ca\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/zenwood.es\/ca\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/zenwood.es\/ca\/wp-json\/wp\/v2\/comments?post=190"}],"version-history":[{"count":26,"href":"https:\/\/zenwood.es\/ca\/wp-json\/wp\/v2\/pages\/190\/revisions"}],"predecessor-version":[{"id":5001,"href":"https:\/\/zenwood.es\/ca\/wp-json\/wp\/v2\/pages\/190\/revisions\/5001"}],"wp:attachment":[{"href":"https:\/\/zenwood.es\/ca\/wp-json\/wp\/v2\/media?parent=190"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}